 {"id":60624,"date":"2026-05-12T10:26:31","date_gmt":"2026-05-12T13:26:31","guid":{"rendered":"https:\/\/portalmidia.net\/?p=60624"},"modified":"2026-05-12T10:26:31","modified_gmt":"2026-05-12T13:26:31","slug":"mppb-ajuiza-acao-contra-energisa-por-irregularidades-em-postes-e-requer-condenacao-por-dano-ambiental-de-r-5-milhoes","status":"publish","type":"post","link":"https:\/\/portalmidia.net\/index.php\/2026\/05\/12\/mppb-ajuiza-acao-contra-energisa-por-irregularidades-em-postes-e-requer-condenacao-por-dano-ambiental-de-r-5-milhoes\/","title":{"rendered":"MPPB aju\u00edza a\u00e7\u00e3o contra Energisa por irregularidades em postes e requer condena\u00e7\u00e3o por dano ambiental de R$ 5 milh\u00f5es"},"content":{"rendered":"<p>O Minist\u00e9rio P\u00fablico da Para\u00edba (MPPB) ajuizou uma a\u00e7\u00e3o civil p\u00fablica por dano ambiental em face da Energisa Distribuidora de Energia El\u00e9trica SA, em raz\u00e3o do grave quadro de desorganiza\u00e7\u00e3o da infraestrutura a\u00e9rea urbana do Munic\u00edpio de Jo\u00e3o Pessoa, caracterizado pela exist\u00eancia disseminada de fios soltos, cabos pendurados, emaranhados, estruturas em desuso e ocupa\u00e7\u00f5es irregulares da rede compartilhada instalada nos postes de energia el\u00e9trica, em desconformidade com as normas t\u00e9cnicas e regulat\u00f3rias aplic\u00e1veis.<\/p>\n<p>A A\u00e7\u00e3o 0833623-34.2026.8.15.2001 foi proposta pela 43\u00aa promotora de Justi\u00e7a de Jo\u00e3o Pessoa, Cl\u00e1udia Cabral, que atua na defesa do meio ambiente e tramita na 1\u00aa Vara da Fazenda P\u00fablica da Capital. Nela, o MPPB requer a concess\u00e3o da tutela de urg\u00eancia para determinar que a distribuidora de energia el\u00e9trica apresente, no prazo de at\u00e9 60 dias, Plano Estrutural de A\u00e7\u00e3o e Regulariza\u00e7\u00e3o da Infraestrutura A\u00e9rea Urbana no munic\u00edpio, com o mapeamento das \u00e1reas de ocupa\u00e7\u00e3o irregular da rede compartilhada; identifica\u00e7\u00e3o, em toda a cidade, de cabeamentos clandestinos, fios em desuso, estruturas penduradas e demais situa\u00e7\u00f5es de risco \u00e0 coletividade e n\u00famero de postes com irregularidades t\u00e9cnicas e polui\u00e7\u00e3o visual; dentre outras medidas, com destaque para a\u00e7\u00f5es fiscalizat\u00f3rias e inspe\u00e7\u00f5es t\u00e9cnicas, sob pena de multa di\u00e1ria n\u00e3o inferior a R$ 10 mil.<\/p>\n<p>Pede tamb\u00e9m que a a\u00e7\u00e3o seja julgada procedente, com a condena\u00e7\u00e3o da empresa ao pagamento de indeniza\u00e7\u00e3o pelos danos coletivos causados ao meio ambiente artificial urbano, \u00e0 paisagem da cidade e \u00e0 ordem urban\u00edstica, em valor a ser arbitrado pelo Ju\u00edzo, n\u00e3o inferior a R$ 5 milh\u00f5es, a ser revertido em favor do Fundo Especial de Prote\u00e7\u00e3o dos Bens, Valores e Interesses Difusos do Estado da Para\u00edba (FDD-PB).<\/p>\n<p>Investiga\u00e7\u00e3o<\/p>\n<p>Conforme explicou a promotora de Justi\u00e7a, a a\u00e7\u00e3o \u00e9 um desdobramento do Inqu\u00e9rito Civil P\u00fablico Inqu\u00e9rito Civil 001.2021.068006, instaurado para averiguar den\u00fancia enviada \u00e0 Ouvidoria do MPPB contra empresas de instala\u00e7\u00e3o de rede de fibra \u00f3tica, que estariam utilizando postes em vias p\u00fablicas, principalmente nos bairros do Bessa e Mana\u00edra, deixando cabos e fios emaranhados e pendurados pelas cal\u00e7adas, fora de padroniza\u00e7\u00e3o, causando transtornos aos transeuntes e colocando-os em risco iminente de acidentes.<\/p>\n<p>Segundo Claudia Cabral, desde os atos iniciais de instru\u00e7\u00e3o, constatou-se que a problem\u00e1tica investigada ultrapassa situa\u00e7\u00f5es isoladas de manuten\u00e7\u00e3o urbana, revelando cen\u00e1rio persistente de precariza\u00e7\u00e3o da rede a\u00e9rea compartilhada, com impactos diretos sobre a seguran\u00e7a da popula\u00e7\u00e3o, a mobilidade urbana, a acessibilidade, a paisagem da cidade e a adequada frui\u00e7\u00e3o do espa\u00e7o p\u00fablico.<\/p>\n<p>No curso da investiga\u00e7\u00e3o ministerial, foram expedidas diversas requisi\u00e7\u00f5es administrativas \u00e0 concession\u00e1ria Energisa Para\u00edba, bem como \u00e0s empresas de telecomunica\u00e7\u00f5es atuantes no munic\u00edpio, buscando-se esclarecer as medidas adotadas para fiscaliza\u00e7\u00e3o, regulariza\u00e7\u00e3o, identifica\u00e7\u00e3o de ocupantes da rede a\u00e9rea e retirada de cabeamentos irregulares, clandestinos ou em desuso.<\/p>\n<p>\u201cAs respostas encaminhadas pelas empresas investigadas revelaram quadro reiterado de fragmenta\u00e7\u00e3o operacional, aus\u00eancia de governan\u00e7a integrada e insufici\u00eancia das medidas at\u00e9 ent\u00e3o implementadas para solu\u00e7\u00e3o efetiva da problem\u00e1tica urbana constatada. A Energisa reconheceu expressamente a exist\u00eancia de ocupa\u00e7\u00f5es irregulares e clandestinas na infraestrutura sob sua gest\u00e3o, admitindo, inclusive, os riscos decorrentes da desorganiza\u00e7\u00e3o da rede a\u00e9rea urbana e os impactos sobre a seguran\u00e7a da popula\u00e7\u00e3o e a integridade do servi\u00e7o essencial de distribui\u00e7\u00e3o de energia el\u00e9trica. Tamb\u00e9m informou a ado\u00e7\u00e3o de iniciativas administrativas e operacionais de fiscaliza\u00e7\u00e3o e regulariza\u00e7\u00e3o, dentre elas a denominada Opera\u00e7\u00e3o Retira Fios realizada de forma pontual nos anos anteriores sem ter contudo continuidade e resolutividade. \u00a0Ao ser ouvida em audi\u00eancia, reconheceu expressamente que det\u00e9m prerrogativa normativa para atua\u00e7\u00e3o em situa\u00e7\u00f5es de risco e que a ocupa\u00e7\u00e3o irregular da rede pode comprometer a seguran\u00e7a do servi\u00e7o p\u00fablico essencial\u201d, explicou a promotora de Justi\u00e7a.<\/p>\n<p>As empresas de telecomunica\u00e7\u00f5es tamb\u00e9m reconheceram a exist\u00eancia da desorganiza\u00e7\u00e3o estrutural da rede a\u00e9rea urbana, atribuindo parte significativa do problema \u00e0 atua\u00e7\u00e3o de ocupantes clandestinos e \u00e0 aus\u00eancia de controle centralizado da ocupa\u00e7\u00e3o dos postes. \u00a0\u201cDa an\u00e1lise conjunta das manifesta\u00e7\u00f5es colhidas no Inqu\u00e9rito Civil, consolidou-se diagn\u00f3stico institucional inequ\u00edvoco acerca da exist\u00eancia de desorganiza\u00e7\u00e3o generalizada da rede a\u00e9rea urbana. As irregularidades verificadas n\u00e3o representam apenas desconforto visual ou simples defici\u00eancia est\u00e9tica urbana. Ao contr\u00e1rio, os elementos coligidos nos autos evidenciam situa\u00e7\u00e3o permanente de risco \u00e0 coletividade, com potencial comprometimento da integridade f\u00edsica de pedestres, motociclistas, ciclistas e condutores de ve\u00edculos, al\u00e9m de preju\u00edzos diretos \u00e0 acessibilidade urbana e ao adequado funcionamento dos espa\u00e7os p\u00fablicos. Al\u00e9m disso, a situa\u00e7\u00e3o constatada configura inequ\u00edvoca degrada\u00e7\u00e3o do meio ambiente artificial urbano, notadamente em raz\u00e3o da polui\u00e7\u00e3o visual ocasionada pelo ac\u00famulo desordenado de cabeamentos excedentes, clandestinos, inativos ou tecnicamente irregulares, comprometendo a paisagem urbana e a adequada organiza\u00e7\u00e3o est\u00e9tica da cidade\u201d, disse Cl\u00e1udia.<\/p>\n<p>A a\u00e7\u00e3o est\u00e1 fundamentada no artigo 225 da Constitui\u00e7\u00e3o Federal, que estabelece o direito de todos ao meio ambiente ecologicamente equilibrado; na legisla\u00e7\u00e3o ambiental e consumerista vigente, no C\u00f3digo de Postura do Munic\u00edpio de Jo\u00e3o Pessoa, dentre outras normas pertinentes \u00e0 mat\u00e9ria.<\/p>\n<p>Confira os pedidos feitos pelo MPPB na a\u00e7\u00e3o:<\/p>\n<p>Em sede liminar:<\/p>\n<p>que seja determinado \u00e0 Energisa Para\u00edba que apresente, no prazo m\u00e1ximo de at\u00e9 60 dias, Plano Estrutural de A\u00e7\u00e3o e Regulariza\u00e7\u00e3o da Infraestrutura A\u00e9rea Urbana do Munic\u00edpio de Jo\u00e3o Pessoa\/PB, contendo: i) mapeamento das \u00e1reas de ocupa\u00e7\u00e3o irregular da rede compartilhada, com identifica\u00e7\u00e3o, em toda cidade, de cabeamentos clandestinos, fios em desuso, estruturas penduradas e demais situa\u00e7\u00f5es de risco \u00e0 coletividade e n\u00fameros de postes com irregularidades t\u00e9cnicas e com polui\u00e7\u00e3o visual; ii) metodologia operacional e divis\u00e3o territorial de atua\u00e7\u00e3o conforme n\u00edveis de criticidade e grau de risco \u00e0 seguran\u00e7a da popula\u00e7\u00e3o; iii) cronograma progressivo de execu\u00e7\u00e3o das medidas de regulariza\u00e7\u00e3o e fiscaliza\u00e7\u00e3o da infraestrutura compartilhada; iv) crit\u00e9rios t\u00e9cnicos permanentes de monitoramento, fiscaliza\u00e7\u00e3o e controle da ocupa\u00e7\u00e3o dos postes urbanos; v) medidas destinadas \u00e0 retirada priorit\u00e1ria de estruturas que apresentem risco concreto \u00e0 seguran\u00e7a da coletividade;<\/p>\n<p>que seja determinado \u00e0 empresa a implementar, no mesmo prazo, o cronograma e o sistema cont\u00ednuo e permanente de fiscaliza\u00e7\u00e3o da ocupa\u00e7\u00e3o da infraestrutura de postes compartilhada, mediante realiza\u00e7\u00e3o peri\u00f3dica de inspe\u00e7\u00f5es t\u00e9cnicas, identifica\u00e7\u00e3o de ocupantes irregulares e ado\u00e7\u00e3o das provid\u00eancias administrativas necess\u00e1rias \u00e0 regulariza\u00e7\u00e3o da rede \u00a0de postes da cidade de Jo\u00e3o Pessoa;<\/p>\n<p>a fixa\u00e7\u00e3o de multa di\u00e1ria em valor n\u00e3o inferior a R$ 10 mil para hip\u00f3tese de descumprimento das obriga\u00e7\u00f5es impostas em sede liminar, sem preju\u00edzo da ado\u00e7\u00e3o de outras medidas executivas necess\u00e1rias \u00e0 efetiva\u00e7\u00e3o da tutela jurisdicional coletiva;<\/p>\n<p>No julgamento da a\u00e7\u00e3o:<\/p>\n<p>a invers\u00e3o do \u00f4nus da prova, nos termos do artigo 6\u00ba, inciso VIII, do C\u00f3digo de Defesa do Consumidor, diante da natureza coletiva da demanda, da hipossufici\u00eancia t\u00e9cnica da coletividade substitu\u00edda e da manifesta assimetria informacional existente entre as partes;<\/p>\n<p>a cita\u00e7\u00e3o da requerida para, querendo, apresentar contesta\u00e7\u00e3o, sob pena de revelia e confiss\u00e3o quanto \u00e0 mat\u00e9ria de fato;<\/p>\n<p>ao final, a total proced\u00eancia da a\u00e7\u00e3o civil p\u00fablica, para confirmar integralmente as medidas concedidas em tutela de urg\u00eancia e condenar a Energisa nas seguintes obriga\u00e7\u00f5es de fazer:<\/p>\n<p>a) apresentar o Plano Estrutural de A\u00e7\u00e3o e Regulariza\u00e7\u00e3o da Infraestrutura A\u00e9rea Urbana do Munic\u00edpio de Jo\u00e3o Pessoa\/PB, contendo: I) mapeamento das \u00e1reas de ocupa\u00e7\u00e3o irregular da rede compartilhada, com identifica\u00e7\u00e3o, em toda cidade, de cabeamentos clandestinos, fios em desuso, estruturas penduradas e demais situa\u00e7\u00f5es de risco \u00e0 coletividade e n\u00fameros de postes com irregularidades t\u00e9cnicas e com polui\u00e7\u00e3o visual; II) metodologia operacional e divis\u00e3o territorial de atua\u00e7\u00e3o conforme n\u00edveis de criticidade e grau de risco \u00e0 seguran\u00e7a da popula\u00e7\u00e3o; III) cronograma progressivo de execu\u00e7\u00e3o das medidas de regulariza\u00e7\u00e3o e fiscaliza\u00e7\u00e3o da infraestrutura compartilhada; IV) crit\u00e9rios t\u00e9cnicos permanentes de monitoramento, fiscaliza\u00e7\u00e3o e controle da ocupa\u00e7\u00e3o dos postes urbanos; V) medidas destinadas \u00e0 retirada priorit\u00e1ria de estruturas que apresentem risco concreto \u00e0 seguran\u00e7a da coletividade;<\/p>\n<p>b) a condena\u00e7\u00e3o da requerida ao pagamento de indeniza\u00e7\u00e3o pelos danos ambientais coletivos causados ao meio ambiente artificial urbano, \u00e0 paisagem da cidade e \u00e0 ordem urban\u00edstica, em valor a ser arbitrado pelo Ju\u00edzo, n\u00e3o inferior a R$ 5 milh\u00f5es, corrigido monetariamente e acrescido de juros de mora, a ser revertido em favor do FDD-PB;<\/p>\n<p>c) a condena\u00e7\u00e3o da requerida ao pagamento das custas processuais e demais \u00f4nus sucumbenciais eventualmente incidentes, bem como a produ\u00e7\u00e3o de todos os meios de prova em direito admitidos, especialmente prova documental complementar, pericial, t\u00e9cnica e inspe\u00e7\u00e3o judicial, caso necess\u00e1rias ao pleno esclarecimento dos fatos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Imagem ilustrativa: Magnific<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico da Para\u00edba (MPPB) ajuizou uma a\u00e7\u00e3o civil p\u00fablica por dano ambiental em face da Energisa Distribuidora de Energia El\u00e9trica SA, em raz\u00e3o do grave quadro de desorganiza\u00e7\u00e3o da infraestrutura a\u00e9rea urbana do Munic\u00edpio de Jo\u00e3o Pessoa, caracterizado pela exist\u00eancia disseminada de fios soltos, cabos pendurados, emaranhados, estruturas em desuso e ocupa\u00e7\u00f5es irregulares<\/p>\n","protected":false},"author":5,"featured_media":60625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-60624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-sexualidade-e-comportamento"],"_links":{"self":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts\/60624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/comments?post=60624"}],"version-history":[{"count":1,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts\/60624\/revisions"}],"predecessor-version":[{"id":60626,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts\/60624\/revisions\/60626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/media\/60625"}],"wp:attachment":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/media?parent=60624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/categories?post=60624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/tags?post=60624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}