 {"id":60633,"date":"2026-05-12T10:36:44","date_gmt":"2026-05-12T13:36:44","guid":{"rendered":"https:\/\/portalmidia.net\/?p=60633"},"modified":"2026-05-12T10:43:04","modified_gmt":"2026-05-12T13:43:04","slug":"dentista-e-presa-suspeita-de-levar-celular-e-drogas-para-presidio-em-joao-pessoa","status":"publish","type":"post","link":"https:\/\/portalmidia.net\/index.php\/2026\/05\/12\/dentista-e-presa-suspeita-de-levar-celular-e-drogas-para-presidio-em-joao-pessoa\/","title":{"rendered":"Dentista \u00e9 presa suspeita de levar celular e drogas para pres\u00eddio em Jo\u00e3o Pessoa"},"content":{"rendered":"<p>Uma dentista foi conduzida \u00e0 delegacia, nesta segunda-feira (11), suspeita de levar aparelhos eletr\u00f4nicos e subst\u00e2ncias il\u00edcitas para detentos da Penitenci\u00e1ria Desembargador S\u00edlvio Porto, em Jo\u00e3o Pessoa.<\/p>\n<p>Segundo informa\u00e7\u00f5es da Secretaria de Estado da Administra\u00e7\u00e3o Penitenci\u00e1ria da Para\u00edba (Seap-PB), a descoberta ocorreu ap\u00f3s um atendimento odontol\u00f3gico. Durante um procedimento de seguran\u00e7a, policiais penais apreenderam com um detento um aparelho celular, carregadores e fones de ouvido.<\/p>\n<p>Questionado, o interno afirmou ter recebido o material da dentista respons\u00e1vel pelo atendimento. Em seguida, a profissional foi abordada e, segundo a Seap, foi flagrada tentando esconder subst\u00e2ncias il\u00edcitas.<\/p>\n<p>Ainda conforme apurado, cada aparelho era R$ 10 MIL REAIS.<\/p>\n<p>A dentista foi conduzida \u00e0 Central de Pol\u00edcia e autuada em flagrante pelos crimes de tr\u00e1fico de drogas e favorecimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma dentista foi conduzida \u00e0 delegacia, nesta segunda-feira (11), suspeita de levar aparelhos eletr\u00f4nicos e subst\u00e2ncias il\u00edcitas para detentos da Penitenci\u00e1ria Desembargador S\u00edlvio Porto, em Jo\u00e3o Pessoa. Segundo informa\u00e7\u00f5es da Secretaria de Estado da Administra\u00e7\u00e3o Penitenci\u00e1ria da Para\u00edba (Seap-PB), a descoberta ocorreu ap\u00f3s um atendimento odontol\u00f3gico. Durante um procedimento de seguran\u00e7a, policiais penais apreenderam com<\/p>\n","protected":false},"author":5,"featured_media":60634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-60633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"_links":{"self":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts\/60633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/comments?post=60633"}],"version-history":[{"count":3,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts\/60633\/revisions"}],"predecessor-version":[{"id":60637,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/posts\/60633\/revisions\/60637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/media\/60634"}],"wp:attachment":[{"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/media?parent=60633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/categories?post=60633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmidia.net\/index.php\/wp-json\/wp\/v2\/tags?post=60633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}